{"id":254,"date":"2024-07-25T07:35:22","date_gmt":"2024-07-25T05:35:22","guid":{"rendered":"https:\/\/wassersportverein-tegel-sued.de\/?p=254"},"modified":"2024-07-25T07:35:22","modified_gmt":"2024-07-25T05:35:22","slug":"uebernachtungsfahrt-vom-20-07-zum-21-07","status":"publish","type":"post","link":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/uebernachtungsfahrt-vom-20-07-zum-21-07\/","title":{"rendered":"\u00dcbernachtungsfahrt vom 20.07. zum 21.07."},"content":{"rendered":"\n<p>Am Samstag haben wir uns nach einer kurzen Diskussion im Verein daf\u00fcr entschieden keine Fahrt auf den Wannsee zu machen, da dort vielen Blaualgen von anderen Bootsbesitzern berichtet wurden. Dadurch ist das Schleusen leider weggefallen, aber Schwimmen im saubereren Wasser wurde h\u00f6her priorisiert als das Schleusen. Am Nachmittag sind wir dann los und haben nach einer kleinen Runde auf dem Nieder Neuendorfer See uns in der N\u00e4he von der Badestelle Sandhausen einen Ankerplatz f\u00fcr die 6 Boote, die teilgenommen haben, gesichert. Hier haben wir dann den Abend mit Gespr\u00e4chen , Grillen und etwas Trinken verbracht. Am n\u00e4chsten Morgen haben wir gefr\u00fchst\u00fcckt und sind wegen den hohen Temperaturen viel im Wasser gewesen. Am sp\u00e4ten Nachmittag wurde wegen der Gefahr eines Gewitters das P\u00e4ckchen aufgel\u00f6st und wir sind wieder Richtung Verein gefahren.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-5 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"259\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan-300x169.jpg\" alt=\"\" class=\"wp-image-259\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Stefan.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"257\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico-300x169.jpg\" alt=\"\" class=\"wp-image-257\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Nico.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"260\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss-300x169.jpg\" alt=\"\" class=\"wp-image-260\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Gruss.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"263\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben-300x169.jpg\" alt=\"\" class=\"wp-image-263\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Oben.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"255\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten-300x169.jpg\" alt=\"\" class=\"wp-image-255\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Hinten.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"256\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne-300x169.jpg\" alt=\"\" class=\"wp-image-256\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Paeckchen_Vorne.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" data-id=\"261\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo-225x300.jpg\" alt=\"\" class=\"wp-image-261\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo-225x300.jpg 225w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo-810x1080.jpg 810w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo-768x1024.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo-1152x1536.jpg 1152w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/ThomasUdo.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" data-id=\"258\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen-300x225.jpg\" alt=\"\" class=\"wp-image-258\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen-300x225.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen-1440x1080.jpg 1440w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen-768x576.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen-1536x1152.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Essen.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"262\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1-300x169.jpg\" alt=\"\" class=\"wp-image-262\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Thomas-1.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" data-id=\"267\" src=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-300x169.jpg\" alt=\"\" class=\"wp-image-267\" srcset=\"https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-300x169.jpg 300w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-768x432.jpg 768w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-1536x864.jpg 1536w, https:\/\/wassersportverein-tegel-sued.de\/wp-content\/uploads\/2024\/07\/Mondschein-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00dcbernachtungsfahrt 2024\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/WX7yxw9NgMs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Am Samstag haben wir uns nach einer kurzen Diskussion im Verein daf\u00fcr entschieden keine Fahrt auf den Wannsee zu machen, da dort vielen Blaualgen von anderen Bootsbesitzern berichtet wurden. Dadurch ist das Schleusen leider weggefallen, aber Schwimmen im saubereren Wasser wurde h\u00f6her priorisiert als das Schleusen. Am Nachmittag sind wir dann los und haben nach &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/wassersportverein-tegel-sued.de\/index.php\/uebernachtungsfahrt-vom-20-07-zum-21-07\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e\u00dcbernachtungsfahrt vom 20.07. zum 21.07.\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-254","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/posts\/254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/comments?post=254"}],"version-history":[{"count":0,"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/posts\/254\/revisions"}],"wp:attachment":[{"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/media?parent=254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/categories?post=254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wassersportverein-tegel-sued.de\/index.php\/wp-json\/wp\/v2\/tags?post=254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}